{"id":2404,"date":"2024-04-28T16:47:35","date_gmt":"2024-04-28T08:47:35","guid":{"rendered":"https:\/\/www.toowin-wpc.com\/2024-new-year-holiday\/"},"modified":"2024-04-28T17:10:29","modified_gmt":"2024-04-28T09:10:29","slug":"2024-new-year-holiday","status":"publish","type":"post","link":"https:\/\/www.toowin-wpc.com\/es\/vacaciones-de-ano-nuevo-2024\/","title":{"rendered":"FIESTA del D\u00cdA INTERNACIONAL DEL TRABAJO"},"content":{"rendered":"<p class=\"has-medium-font-size\">Queridos clientes<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00a1Feliz D\u00eda del Trabajo!<br>De acuerdo con las pol\u00edticas nacionales pertinentes y en combinaci\u00f3n con la situaci\u00f3n actual de la empresa, nos gustar\u00eda informarle que nuestro feriado del d\u00eda del trabajo ser\u00e1 del 1 de mayo de 2024 al 5 de mayo de 2024, en total 5 d\u00edas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"484\" src=\"https:\/\/ljcloudglobal.oss-cn-hongkong.aliyuncs.com\/wp-content\/uploads\/tuwei\/2024\/04\/SRC_HT1.gif\" alt=\"fabricante en venta\" class=\"wp-image-2406\"><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">No se preocupe, todos sus pedidos est\u00e1n bien organizados y mantienen la entrega seg\u00fan lo planeado. Y todos los miembros de nuestro equipo de ventas todav\u00eda est\u00e1n en l\u00ednea, si tiene alguna pregunta. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Debido al buen negocio este a\u00f1o, si tiene alg\u00fan pedido, confirme lo antes posible.<br>Gracias por tu atenci\u00f3n.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Atentamente<br>Toowin<\/p>","protected":false},"excerpt":{"rendered":"<p>Estimados clientes, \u00a1Feliz D\u00eda del Trabajo! De acuerdo con las pol\u00edticas nacionales pertinentes y en combinaci\u00f3n con la situaci\u00f3n real de la empresa, nos gustar\u00eda informarles que nuestro feriado del D\u00eda del Trabajo ser\u00e1 del 1 de mayo de 2024 al 5 de mayo de 2024, en total 5 d\u00edas. . Por favor, no se preocupe, todos sus pedidos est\u00e1n bien organizados [\u2026]<\/p>","protected":false},"author":2,"featured_media":2408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[125],"class_list":["post-2404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-news","tag-news"],"_links":{"self":[{"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/posts\/2404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/comments?post=2404"}],"version-history":[{"count":4,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/posts\/2404\/revisions"}],"predecessor-version":[{"id":2411,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/posts\/2404\/revisions\/2411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/media\/2408"}],"wp:attachment":[{"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/media?parent=2404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/categories?post=2404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toowin-wpc.com\/es\/wp-json\/wp\/v2\/tags?post=2404"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}